{"id":3563,"date":"2013-11-21T18:05:22","date_gmt":"2013-11-21T18:05:22","guid":{"rendered":"http:\/\/cece.org\/nuevo-espacio\/?p=3563"},"modified":"2013-11-22T21:27:41","modified_gmt":"2013-11-22T21:27:41","slug":"convocatoria-naciones-unidas","status":"publish","type":"post","link":"http:\/\/cece.org\/nuevo-espacio\/convocatoria-naciones-unidas\/","title":{"rendered":"Convocatoria Naciones Unidas"},"content":{"rendered":"<p><strong>En conmemoraci\u00f3n por el 70\u00ba Aniversario de Naciones Unidas, el Programa UNAI (United Nations Academic Impact) invita a todos los estudiantes mayores de 18 a\u00f1os a participar del Concurso de Ensayos sobre Multiling\u00fcismo.<\/strong><br \/>\nQuienes deseen participar, deber\u00e1n presentar un ensayo sobre el rol del multiling\u00fcismo en el mundo globalizado que no exceda las 2000 palabras. El mismo, podr\u00e1 ser escrito en cualquier idioma oficial de las Naciones Unidas (\u00e1rabe, chino, ingl\u00e9s, franc\u00e9s, ruso y espa\u00f1ol) que no sea el lenguaje nativo del estudiante.<br \/>\nLos ensayos podr\u00e1n presentarse hasta el 21 de febrero de 2014.<br \/>\nLos ganadores ser\u00e1n invitados a participar de una serie de eventos organizados por las Naciones Unidas a realizar en Nueva York entre los d\u00edas 25 y 29 de Junio de 2014.<br \/>\nEl formulario de presentaci\u00f3n podr\u00e1n encontrarlo <a href=\"http:\/\/www.els.edu\/en\/manylanguagesoneworld\" target=\"_blank\"> aqu\u00ed. <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>En conmemoraci\u00f3n por el 70\u00ba Aniversario de Naciones Unidas, el Programa UNAI (United Nations Academic Impact) invita a todos los estudiantes mayores de 18 a\u00f1os a participar del Concurso de Ensayos sobre Multiling\u00fcismo.<\/strong><\/p>\n","protected":false},"author":1,"featured_media":3572,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"blocksy_meta":[],"_links":{"self":[{"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/posts\/3563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/comments?post=3563"}],"version-history":[{"count":0,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/posts\/3563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/posts\/3572"}],"wp:attachment":[{"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/media?parent=3563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/categories?post=3563"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/tags?post=3563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}