{"id":3372,"date":"2013-08-26T16:55:44","date_gmt":"2013-08-26T16:55:44","guid":{"rendered":"http:\/\/cece.org\/nuevo-espacio\/?p=3372"},"modified":"2013-08-26T16:55:44","modified_gmt":"2013-08-26T16:55:44","slug":"vamos-por-la-4ta-materia","status":"publish","type":"post","link":"http:\/\/cece.org\/nuevo-espacio\/vamos-por-la-4ta-materia\/","title":{"rendered":"Vamos por la 4ta. materia!"},"content":{"rendered":"<h6>Desde Nuevo Espacio entendemos que seguir creando nuevas formas y oportunidades de cursada, es seguir incluyendo mas compa\u00f1eros en la Universidad P\u00fablica y, esto es una de las mejores formas de defenderla.<\/h6>\n<p>Desde que asumimos la representaci\u00f3n de los estudiantes a trav\u00e9s del Consejo Directivo de la Facultad venimos impulsando nuevas iniciativas que se han concretado gracias al apoyo de todos ustedes. Entre estas podemos contar los Cursos Intensivos de Verano, los Cursos Intensivos de Invierno y la novedosa Modalidad Virtual. Pero el trabajo no se agota en crear nuevas modalidades sino que tambi\u00e9n hay que cuidarlas una vez logradas. Por esto trabajamos en ampliar la oferta. Para el \u00faltimo periodo de invierno, los Consejeros Directivos de Nuevo Espacio presentaron un proyecto para que se incluyan materias de 6 horas, duplicando de esta manera los cursos ofertados.<\/p>\n<p>En esta oportunidad, te pedimos que nos vuelvas a acompa\u00f1ar. En los \u00faltimos a\u00f1os la asignaci\u00f3n de materias viene siendo un proceso mucho m\u00e1s eficiente que abre nuevas puertas. Es por esto que vamos a presentar un proyecto en el Consejo Directivo de la FCE para que todos los estudiantes tengamos la posibilidad cursar una cuarta materia cuatrimestral.<\/p>\n<p>Nuestro proyecto contempla que adem\u00e1s de poder inscribirte en tres materias como hiciste siempre, tengas la posibilidad de anotarte en una cuarta materia en segunda inscripci\u00f3n. As\u00ed durante el cuatrimestre vas a poder cursar cuatro materias de forma presencial. Por m\u00e1s oferta, mejor cursada y m\u00e1s Universidad P\u00fablica. Sumate a acompa\u00f1ar este proyecto, para seguir construyendo juntos, la mejor facultad de la UBA.<\/p>\n<p>\u00a1Ya lo logramos para el CBC, con tu ayuda podemos lograrlo para toda la carrera! Firm\u00e1 el petitorio en la mesa de Nuevo Espacio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;vamos a presentar un proyecto en el Consejo Directivo de la FCE para que todos los estudiantes tengamos la posibilidad cursar una cuarta materia cuatrimestral. [&#8230;] &#8230;y tengas la posibilidad de anotarte en una cuarta materia en segunda inscripci\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":3374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[33],"tags":[],"class_list":["post-3372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuevo-espacio-en-el-cece-y-el-consejo"],"blocksy_meta":[],"_links":{"self":[{"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/posts\/3372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/comments?post=3372"}],"version-history":[{"count":0,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/posts\/3372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/posts\/3374"}],"wp:attachment":[{"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/media?parent=3372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/categories?post=3372"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cece.org\/nuevo-espacio\/wp-json\/wp\/v2\/tags?post=3372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}